{"id":22663,"date":"2023-05-22T15:05:58","date_gmt":"2023-05-22T15:05:58","guid":{"rendered":"https:\/\/www.cambusawine.com\/?post_type=product&#038;p=22663"},"modified":"2023-10-20T21:18:38","modified_gmt":"2023-10-20T21:18:38","slug":"i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt","status":"publish","type":"product","link":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/","title":{"rendered":"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":22665,"template":"","meta":[],"product_brand":[],"product_cat":[161,115],"product_tag":[],"class_list":{"0":"post-22663","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magnum-and-large-format","7":"product_cat-red-wine","8":"Producer-castellare","9":"Bottle_Size-magnum-1-5l","10":"Appellation-colli-della-toscana-centrale-igp","11":"Appellation-toscana-igp","12":"region-toscana","13":"grape-malvasia-nera","14":"grape-sangioveto","15":"vintage-2758","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt - Wine Shop La Cambusa Stresa<\/title>\n<meta name=\"description\" content=\"I Sodi di San Nicol\u00f2 1997 Colli della Toscana Centrale Castellare is a red wine made by Malvasia nera, Sangioveto in Tuscany (Italy). Castellare, Colli della Toscana Centrale IGP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt - Wine Shop La Cambusa Stresa\" \/>\n<meta property=\"og:description\" content=\"I Sodi di San Nicol\u00f2 1997 Colli della Toscana Centrale Castellare is a red wine made by Malvasia nera, Sangioveto in Tuscany (Italy). Castellare, Colli della Toscana Centrale IGP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/\" \/>\n<meta property=\"og:site_name\" content=\"Wine Shop La Cambusa Stresa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LacambusaStresa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T21:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/05\/castellare-magnum-2019-toscana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"539\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/\",\"url\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/\",\"name\":\"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt - Wine Shop La Cambusa Stresa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambusawine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/castellare-magnum-2019-toscana.jpg\",\"datePublished\":\"2023-05-22T15:05:58+00:00\",\"dateModified\":\"2023-10-20T21:18:38+00:00\",\"description\":\"I Sodi di San Nicol\u00f2 1997 Colli della Toscana Centrale Castellare is a red wine made by Malvasia nera, Sangioveto in Tuscany (Italy). Castellare, Colli della Toscana Centrale IGP.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cambusawine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/castellare-magnum-2019-toscana.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambusawine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/castellare-magnum-2019-toscana.jpg\",\"width\":539,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/prodotto\\\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/\",\"name\":\"Wine Shop La Cambusa Stresa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/#organization\",\"name\":\"Wine Shop La Cambusa Stresa\",\"url\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cambusawine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/la-cambusa-logo-nero.png\",\"contentUrl\":\"https:\\\/\\\/www.cambusawine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/la-cambusa-logo-nero.png\",\"width\":340,\"height\":156,\"caption\":\"Wine Shop La Cambusa Stresa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambusawine.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LacambusaStresa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lacambusa_stresa_wineshop\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt - Wine Shop La Cambusa Stresa","description":"I Sodi di San Nicol\u00f2 1997 Colli della Toscana Centrale Castellare is a red wine made by Malvasia nera, Sangioveto in Tuscany (Italy). Castellare, Colli della Toscana Centrale IGP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/","og_locale":"it_IT","og_type":"article","og_title":"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt - Wine Shop La Cambusa Stresa","og_description":"I Sodi di San Nicol\u00f2 1997 Colli della Toscana Centrale Castellare is a red wine made by Malvasia nera, Sangioveto in Tuscany (Italy). Castellare, Colli della Toscana Centrale IGP.","og_url":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/","og_site_name":"Wine Shop La Cambusa Stresa","article_publisher":"https:\/\/www.facebook.com\/LacambusaStresa\/","article_modified_time":"2023-10-20T21:18:38+00:00","og_image":[{"width":539,"height":534,"url":"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/05\/castellare-magnum-2019-toscana.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/","url":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/","name":"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt - Wine Shop La Cambusa Stresa","isPartOf":{"@id":"https:\/\/www.cambusawine.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/#primaryimage"},"image":{"@id":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/05\/castellare-magnum-2019-toscana.jpg","datePublished":"2023-05-22T15:05:58+00:00","dateModified":"2023-10-20T21:18:38+00:00","description":"I Sodi di San Nicol\u00f2 1997 Colli della Toscana Centrale Castellare is a red wine made by Malvasia nera, Sangioveto in Tuscany (Italy). Castellare, Colli della Toscana Centrale IGP.","breadcrumb":{"@id":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/#primaryimage","url":"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/05\/castellare-magnum-2019-toscana.jpg","contentUrl":"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/05\/castellare-magnum-2019-toscana.jpg","width":539,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/www.cambusawine.com\/it\/prodotto\/i-sodi-di-san-nicolo-2019-colli-della-toscana-centrale-castellare-15-lt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cambusawine.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.cambusawine.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"I Sodi di San Nicol\u00f2 2019 Colli della Toscana Centrale Castellare 1,5 lt"}]},{"@type":"WebSite","@id":"https:\/\/www.cambusawine.com\/it\/#website","url":"https:\/\/www.cambusawine.com\/it\/","name":"Wine Shop La Cambusa Stresa","description":"","publisher":{"@id":"https:\/\/www.cambusawine.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cambusawine.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.cambusawine.com\/it\/#organization","name":"Wine Shop La Cambusa Stresa","url":"https:\/\/www.cambusawine.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cambusawine.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/09\/la-cambusa-logo-nero.png","contentUrl":"https:\/\/www.cambusawine.com\/wp-content\/uploads\/2023\/09\/la-cambusa-logo-nero.png","width":340,"height":156,"caption":"Wine Shop La Cambusa Stresa"},"image":{"@id":"https:\/\/www.cambusawine.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LacambusaStresa\/","https:\/\/www.instagram.com\/lacambusa_stresa_wineshop\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/product\/22663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/media\/22665"}],"wp:attachment":[{"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/media?parent=22663"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/product_brand?post=22663"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/product_cat?post=22663"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cambusawine.com\/it\/wp-json\/wp\/v2\/product_tag?post=22663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}